{"id":4808,"date":"2023-01-22T22:52:39","date_gmt":"2023-01-22T20:52:39","guid":{"rendered":"https:\/\/savyn.info\/wp-content\/uploads\/2023\/01\/yzobrazhenye_viber_2023-01-22_21-39-05-304.jpg"},"modified":"2023-01-22T22:52:39","modified_gmt":"2023-01-22T20:52:39","slug":"yzobrazhenye_viber_2023-01-22_21-39-05-304","status":"inherit","type":"attachment","link":"https:\/\/savyn.info\/ru\/sviato-sobornosti-kontsert-zhanny-bodnaruk\/yzobrazhenye_viber_2023-01-22_21-39-05-304\/","title":{"rendered":"\u0438\u0437\u043e\u0431\u0440\u0430\u0436\u0435\u043d\u0438\u0435_viber_2023-01-22_21-39-05-304"},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"colormag_page_layout":"default_layout"},"class_list":["post-4808","attachment","type-attachment","status-inherit","hentry"],"smush":{"stats":{"percent":8.05370518809254,"bytes":46620,"size_before":578864,"size_after":532244,"time":0.3500000000000001,"api_version":"1.0","lossy":false,"keep_exif":0},"sizes":{"medium":{"percent":16.17,"bytes":3818,"size_before":23607,"size_after":19789,"time":0.01},"large":{"percent":7.74,"bytes":5108,"size_before":66010,"size_after":60902,"time":0.03},"thumbnail":{"percent":30.87,"bytes":3286,"size_before":10645,"size_after":7359,"time":0.01},"medium_large":{"percent":6.78,"bytes":5494,"size_before":81004,"size_after":75510,"time":0.03},"1536x1536":{"percent":3.66,"bytes":8609,"size_before":234958,"size_after":226349,"time":0.2},"colormag-featured-image":{"percent":7.14,"bytes":5335,"size_before":74765,"size_after":69430,"time":0.02},"colormag-highlighted-post":{"percent":13.22,"bytes":3998,"size_before":30250,"size_after":26252,"time":0.01},"colormag-featured-post-medium":{"percent":15.51,"bytes":3963,"size_before":25552,"size_after":21589,"time":0.02},"colormag-featured-post-small":{"percent":40.08,"bytes":3155,"size_before":7872,"size_after":4717,"time":0.01},"menu-thumb":{"percent":15.92,"bytes":3854,"size_before":24201,"size_after":20347,"time":0.01}}},"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/savyn.info\/wp-content\/uploads\/2023\/01\/yzobrazhenye_viber_2023-01-22_21-39-05-304.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"336\" height=\"223\" src=\"https:\/\/savyn.info\/wp-content\/uploads\/2023\/01\/yzobrazhenye_viber_2023-01-22_21-39-05-304-336x223.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/savyn.info\/wp-content\/uploads\/2023\/01\/yzobrazhenye_viber_2023-01-22_21-39-05-304-336x223.jpg 336w, https:\/\/savyn.info\/wp-content\/uploads\/2023\/01\/yzobrazhenye_viber_2023-01-22_21-39-05-304-671x445.jpg 671w, https:\/\/savyn.info\/wp-content\/uploads\/2023\/01\/yzobrazhenye_viber_2023-01-22_21-39-05-304-768x509.jpg 768w, https:\/\/savyn.info\/wp-content\/uploads\/2023\/01\/yzobrazhenye_viber_2023-01-22_21-39-05-304-1536x1019.jpg 1536w, https:\/\/savyn.info\/wp-content\/uploads\/2023\/01\/yzobrazhenye_viber_2023-01-22_21-39-05-304.jpg 1600w\" sizes=\"auto, (max-width: 336px) 100vw, 336px\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":1600,"height":1061,"file":"2023\/01\/yzobrazhenye_viber_2023-01-22_21-39-05-304.jpg","sizes":{"medium":{"file":"yzobrazhenye_viber_2023-01-22_21-39-05-304-336x223.jpg","width":336,"height":223,"mime_type":"image\/jpeg","source_url":"https:\/\/savyn.info\/wp-content\/uploads\/2023\/01\/yzobrazhenye_viber_2023-01-22_21-39-05-304-336x223.jpg"},"large":{"file":"yzobrazhenye_viber_2023-01-22_21-39-05-304-671x445.jpg","width":671,"height":445,"mime_type":"image\/jpeg","source_url":"https:\/\/savyn.info\/wp-content\/uploads\/2023\/01\/yzobrazhenye_viber_2023-01-22_21-39-05-304-671x445.jpg"},"thumbnail":{"file":"yzobrazhenye_viber_2023-01-22_21-39-05-304-150x150.jpg","width":150,"height":150,"mime_type":"image\/jpeg","source_url":"https:\/\/savyn.info\/wp-content\/uploads\/2023\/01\/yzobrazhenye_viber_2023-01-22_21-39-05-304-150x150.jpg"},"medium_large":{"file":"yzobrazhenye_viber_2023-01-22_21-39-05-304-768x509.jpg","width":768,"height":509,"mime_type":"image\/jpeg","source_url":"https:\/\/savyn.info\/wp-content\/uploads\/2023\/01\/yzobrazhenye_viber_2023-01-22_21-39-05-304-768x509.jpg"},"1536x1536":{"file":"yzobrazhenye_viber_2023-01-22_21-39-05-304-1536x1019.jpg","width":1536,"height":1019,"mime_type":"image\/jpeg","source_url":"https:\/\/savyn.info\/wp-content\/uploads\/2023\/01\/yzobrazhenye_viber_2023-01-22_21-39-05-304-1536x1019.jpg"},"colormag-featured-image":{"file":"yzobrazhenye_viber_2023-01-22_21-39-05-304-800x445.jpg","width":800,"height":445,"mime_type":"image\/jpeg","source_url":"https:\/\/savyn.info\/wp-content\/uploads\/2023\/01\/yzobrazhenye_viber_2023-01-22_21-39-05-304-800x445.jpg"},"colormag-highlighted-post":{"file":"yzobrazhenye_viber_2023-01-22_21-39-05-304-392x272.jpg","width":392,"height":272,"mime_type":"image\/jpeg","source_url":"https:\/\/savyn.info\/wp-content\/uploads\/2023\/01\/yzobrazhenye_viber_2023-01-22_21-39-05-304-392x272.jpg"},"colormag-featured-post-medium":{"file":"yzobrazhenye_viber_2023-01-22_21-39-05-304-390x205.jpg","width":390,"height":205,"mime_type":"image\/jpeg","source_url":"https:\/\/savyn.info\/wp-content\/uploads\/2023\/01\/yzobrazhenye_viber_2023-01-22_21-39-05-304-390x205.jpg"},"colormag-featured-post-small":{"file":"yzobrazhenye_viber_2023-01-22_21-39-05-304-130x90.jpg","width":130,"height":90,"mime_type":"image\/jpeg","source_url":"https:\/\/savyn.info\/wp-content\/uploads\/2023\/01\/yzobrazhenye_viber_2023-01-22_21-39-05-304-130x90.jpg"},"menu-thumb":{"file":"yzobrazhenye_viber_2023-01-22_21-39-05-304-330x230.jpg","width":330,"height":230,"mime_type":"image\/jpeg","source_url":"https:\/\/savyn.info\/wp-content\/uploads\/2023\/01\/yzobrazhenye_viber_2023-01-22_21-39-05-304-330x230.jpg"},"full":{"file":"yzobrazhenye_viber_2023-01-22_21-39-05-304.jpg","width":1600,"height":1061,"mime_type":"image\/jpeg","source_url":"https:\/\/savyn.info\/wp-content\/uploads\/2023\/01\/yzobrazhenye_viber_2023-01-22_21-39-05-304.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0"}},"post":4803,"source_url":"https:\/\/savyn.info\/wp-content\/uploads\/2023\/01\/yzobrazhenye_viber_2023-01-22_21-39-05-304.jpg","_links":{"self":[{"href":"https:\/\/savyn.info\/ru\/wp-json\/wp\/v2\/media\/4808","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/savyn.info\/ru\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/savyn.info\/ru\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/savyn.info\/ru\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/savyn.info\/ru\/wp-json\/wp\/v2\/comments?post=4808"}],"wp:attached-to":[{"embeddable":true,"post_type":"post","id":4803,"href":"https:\/\/savyn.info\/ru\/wp-json\/wp\/v2\/posts\/4803"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}